{"id":667,"date":"2020-07-31T11:35:27","date_gmt":"2020-07-31T14:35:27","guid":{"rendered":"http:\/\/www.zockun.com.br\/?p=667"},"modified":"2020-07-31T11:35:27","modified_gmt":"2020-07-31T14:35:27","slug":"mauricio-zockun-modera-webinar-avaliacao-da-legislacao-brasileira","status":"publish","type":"post","link":"https:\/\/zockun.com.br\/en\/mauricio-zockun-modera-webinar-avaliacao-da-legislacao-brasileira\/","title":{"rendered":"Maur\u00edcio Zockun modera &#8216;webinar&#8217; sobre ades\u00e3o do Brasil ao Acordo de Compras Governamentais (GPA), da OMC"},"content":{"rendered":"<p>Maur\u00edcio Zockun, s\u00f3cio do escrit\u00f3rio, foi o moderador do 5\u00ba encontro da s\u00e9rie de webinars \u201cAdes\u00e3o do Brasil ao GPA\/OMC: Compras Governamentais e Reforma das Licita\u00e7\u00f5es\u201d. Realizado pelo Instituto Brasiliense de Direito P\u00fablico (IDP), o evento &#8216;on line&#8217; vem promovendo debates sobre os temas que desafiar\u00e3o o governo, legisladores e especialistas brasileiros no processo de ingresso do Brasil no GPA\/OMC e na harmoniza\u00e7\u00e3o do sistema de licita\u00e7\u00f5es com os padr\u00f5es internacionais.<\/p>\n<p>O mais recente encontro trouxe o tema \u201cAvalia\u00e7\u00e3o da Legisla\u00e7\u00e3o Brasileira\u201d. Tamb\u00e9m participaram Aris Georgopoulos (Universidade de Nottingham), Paula Faustino (Universidade de Nottingham) e Mar\u00e7al Justen Filho (Professor do IDP).<\/p>\n<p>Confira o conte\u00fado: <a href=\"https:\/\/www.youtube.com\/watch?v=4nZQFk3zqsM&amp;feature=youtu.be\">https:\/\/www.youtube.com\/watch?v=4nZQFk3zqsM&amp;feature=youtu.be<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Maur\u00edcio Zockun, s\u00f3cio do escrit\u00f3rio, foi o moderador do 5\u00ba encontro da s\u00e9rie de webinars \u201cAdes\u00e3o do [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2256,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[8,7],"class_list":["post-667","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-publicacoes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Maur\u00edcio Zockun modera &#039;webinar&#039; sobre ades\u00e3o do Brasil ao Acordo de Compras Governamentais (GPA), da OMC - Zockun e Fleury Advogados<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zockun.com.br\/en\/mauricio-zockun-modera-webinar-avaliacao-da-legislacao-brasileira\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Maur\u00edcio Zockun modera &#039;webinar&#039; sobre ades\u00e3o do Brasil ao Acordo de Compras Governamentais (GPA), da OMC - Zockun e Fleury Advogados\" \/>\n<meta property=\"og:description\" content=\"Maur\u00edcio Zockun, s\u00f3cio do escrit\u00f3rio, foi o moderador do 5\u00ba encontro da s\u00e9rie de webinars \u201cAdes\u00e3o do [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zockun.com.br\/en\/mauricio-zockun-modera-webinar-avaliacao-da-legislacao-brasileira\/\" \/>\n<meta property=\"og:site_name\" content=\"Zockun e Fleury Advogados\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/zockunadvogados\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-31T14:35:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zockun.com.br\/wp-content\/uploads\/2026\/05\/Foto-9-05-1024x576.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/zockun.com.br\\\/mauricio-zockun-modera-webinar-avaliacao-da-legislacao-brasileira\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/mauricio-zockun-modera-webinar-avaliacao-da-legislacao-brasileira\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/zockun.com.br\\\/#\\\/schema\\\/person\\\/7b2361a745fbc8b220437ab210761a33\"},\"headline\":\"Maur\u00edcio Zockun modera &#8216;webinar&#8217; sobre ades\u00e3o do Brasil ao Acordo de Compras Governamentais (GPA), da OMC\",\"datePublished\":\"2020-07-31T14:35:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/mauricio-zockun-modera-webinar-avaliacao-da-legislacao-brasileira\\\/\"},\"wordCount\":151,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/mauricio-zockun-modera-webinar-avaliacao-da-legislacao-brasileira\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zockun.com.br\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Foto-9-05-scaled.png\",\"articleSection\":[\"Not\u00edcias\",\"Publica\u00e7\u00f5es\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/zockun.com.br\\\/mauricio-zockun-modera-webinar-avaliacao-da-legislacao-brasileira\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/mauricio-zockun-modera-webinar-avaliacao-da-legislacao-brasileira\\\/\",\"url\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/mauricio-zockun-modera-webinar-avaliacao-da-legislacao-brasileira\\\/\",\"name\":\"Maur\u00edcio Zockun modera 'webinar' sobre ades\u00e3o do Brasil ao Acordo de Compras Governamentais (GPA), da OMC - Zockun e Fleury Advogados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/mauricio-zockun-modera-webinar-avaliacao-da-legislacao-brasileira\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/mauricio-zockun-modera-webinar-avaliacao-da-legislacao-brasileira\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zockun.com.br\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Foto-9-05-scaled.png\",\"datePublished\":\"2020-07-31T14:35:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/mauricio-zockun-modera-webinar-avaliacao-da-legislacao-brasileira\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/zockun.com.br\\\/en\\\/mauricio-zockun-modera-webinar-avaliacao-da-legislacao-brasileira\\\/\"]]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/mauricio-zockun-modera-webinar-avaliacao-da-legislacao-brasileira\\\/#primaryimage\",\"url\":\"https:\\\/\\\/zockun.com.br\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Foto-9-05-scaled.png\",\"contentUrl\":\"https:\\\/\\\/zockun.com.br\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Foto-9-05-scaled.png\",\"width\":2560,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/mauricio-zockun-modera-webinar-avaliacao-da-legislacao-brasileira\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Maur\u00edcio Zockun modera &#8216;webinar&#8217; sobre ades\u00e3o do Brasil ao Acordo de Compras Governamentais (GPA), da OMC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/\",\"name\":\"Zockun e Fleury Advogados\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/#organization\",\"name\":\"Zockun e Fleury Advogados\",\"url\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/zockun.com.br\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Favicon.jpg\",\"contentUrl\":\"https:\\\/\\\/zockun.com.br\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Favicon.jpg\",\"width\":400,\"height\":400,\"caption\":\"Zockun e Fleury Advogados\"},\"image\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/zockunadvogados\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/zockun-advogados\",\"https:\\\/\\\/www.instagram.com\\\/zockunefleury\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/zockun.com.br\\\/#\\\/schema\\\/person\\\/7b2361a745fbc8b220437ab210761a33\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/zockun.com.br\"],\"url\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Maur\u00edcio Zockun modera 'webinar' sobre ades\u00e3o do Brasil ao Acordo de Compras Governamentais (GPA), da OMC - Zockun e Fleury Advogados","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zockun.com.br\/en\/mauricio-zockun-modera-webinar-avaliacao-da-legislacao-brasileira\/","og_locale":"en_US","og_type":"article","og_title":"Maur\u00edcio Zockun modera 'webinar' sobre ades\u00e3o do Brasil ao Acordo de Compras Governamentais (GPA), da OMC - Zockun e Fleury Advogados","og_description":"Maur\u00edcio Zockun, s\u00f3cio do escrit\u00f3rio, foi o moderador do 5\u00ba encontro da s\u00e9rie de webinars \u201cAdes\u00e3o do [&hellip;]","og_url":"https:\/\/zockun.com.br\/en\/mauricio-zockun-modera-webinar-avaliacao-da-legislacao-brasileira\/","og_site_name":"Zockun e Fleury Advogados","article_publisher":"https:\/\/www.facebook.com\/zockunadvogados","article_published_time":"2020-07-31T14:35:27+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/zockun.com.br\/wp-content\/uploads\/2026\/05\/Foto-9-05-1024x576.png","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/zockun.com.br\/mauricio-zockun-modera-webinar-avaliacao-da-legislacao-brasileira\/#article","isPartOf":{"@id":"https:\/\/zockun.com.br\/mauricio-zockun-modera-webinar-avaliacao-da-legislacao-brasileira\/"},"author":{"name":"admin","@id":"https:\/\/zockun.com.br\/#\/schema\/person\/7b2361a745fbc8b220437ab210761a33"},"headline":"Maur\u00edcio Zockun modera &#8216;webinar&#8217; sobre ades\u00e3o do Brasil ao Acordo de Compras Governamentais (GPA), da OMC","datePublished":"2020-07-31T14:35:27+00:00","mainEntityOfPage":{"@id":"https:\/\/zockun.com.br\/mauricio-zockun-modera-webinar-avaliacao-da-legislacao-brasileira\/"},"wordCount":151,"commentCount":0,"publisher":{"@id":"https:\/\/zockun.com.br\/#organization"},"image":{"@id":"https:\/\/zockun.com.br\/mauricio-zockun-modera-webinar-avaliacao-da-legislacao-brasileira\/#primaryimage"},"thumbnailUrl":"https:\/\/zockun.com.br\/wp-content\/uploads\/2026\/05\/Foto-9-05-scaled.png","articleSection":["Not\u00edcias","Publica\u00e7\u00f5es"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/zockun.com.br\/mauricio-zockun-modera-webinar-avaliacao-da-legislacao-brasileira\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/zockun.com.br\/en\/mauricio-zockun-modera-webinar-avaliacao-da-legislacao-brasileira\/","url":"https:\/\/zockun.com.br\/en\/mauricio-zockun-modera-webinar-avaliacao-da-legislacao-brasileira\/","name":"Maur\u00edcio Zockun modera 'webinar' sobre ades\u00e3o do Brasil ao Acordo de Compras Governamentais (GPA), da OMC - Zockun e Fleury Advogados","isPartOf":{"@id":"https:\/\/zockun.com.br\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/zockun.com.br\/en\/mauricio-zockun-modera-webinar-avaliacao-da-legislacao-brasileira\/#primaryimage"},"image":{"@id":"https:\/\/zockun.com.br\/mauricio-zockun-modera-webinar-avaliacao-da-legislacao-brasileira\/#primaryimage"},"thumbnailUrl":"https:\/\/zockun.com.br\/wp-content\/uploads\/2026\/05\/Foto-9-05-scaled.png","datePublished":"2020-07-31T14:35:27+00:00","breadcrumb":{"@id":"https:\/\/zockun.com.br\/en\/mauricio-zockun-modera-webinar-avaliacao-da-legislacao-brasileira\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/zockun.com.br\/en\/mauricio-zockun-modera-webinar-avaliacao-da-legislacao-brasileira\/"]]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/zockun.com.br\/en\/mauricio-zockun-modera-webinar-avaliacao-da-legislacao-brasileira\/#primaryimage","url":"https:\/\/zockun.com.br\/wp-content\/uploads\/2026\/05\/Foto-9-05-scaled.png","contentUrl":"https:\/\/zockun.com.br\/wp-content\/uploads\/2026\/05\/Foto-9-05-scaled.png","width":2560,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/zockun.com.br\/en\/mauricio-zockun-modera-webinar-avaliacao-da-legislacao-brasileira\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/zockun.com.br\/en\/"},{"@type":"ListItem","position":2,"name":"Maur\u00edcio Zockun modera &#8216;webinar&#8217; sobre ades\u00e3o do Brasil ao Acordo de Compras Governamentais (GPA), da OMC"}]},{"@type":"WebSite","@id":"https:\/\/zockun.com.br\/en\/#website","url":"https:\/\/zockun.com.br\/en\/","name":"Zockun e Fleury Advogados","description":"","publisher":{"@id":"https:\/\/zockun.com.br\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zockun.com.br\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/zockun.com.br\/en\/#organization","name":"Zockun e Fleury Advogados","url":"https:\/\/zockun.com.br\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/zockun.com.br\/en\/#\/schema\/logo\/image\/","url":"https:\/\/zockun.com.br\/wp-content\/uploads\/2025\/10\/Favicon.jpg","contentUrl":"https:\/\/zockun.com.br\/wp-content\/uploads\/2025\/10\/Favicon.jpg","width":400,"height":400,"caption":"Zockun e Fleury Advogados"},"image":{"@id":"https:\/\/zockun.com.br\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/zockunadvogados","https:\/\/www.linkedin.com\/company\/zockun-advogados","https:\/\/www.instagram.com\/zockunefleury\/"]},{"@type":"Person","@id":"https:\/\/zockun.com.br\/#\/schema\/person\/7b2361a745fbc8b220437ab210761a33","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/zockun.com.br"],"url":"https:\/\/zockun.com.br\/en\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/zockun.com.br\/en\/wp-json\/wp\/v2\/posts\/667","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zockun.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zockun.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zockun.com.br\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zockun.com.br\/en\/wp-json\/wp\/v2\/comments?post=667"}],"version-history":[{"count":0,"href":"https:\/\/zockun.com.br\/en\/wp-json\/wp\/v2\/posts\/667\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zockun.com.br\/en\/wp-json\/wp\/v2\/media\/2256"}],"wp:attachment":[{"href":"https:\/\/zockun.com.br\/en\/wp-json\/wp\/v2\/media?parent=667"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zockun.com.br\/en\/wp-json\/wp\/v2\/categories?post=667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}