{"id":2341,"date":"2026-07-15T11:25:10","date_gmt":"2026-07-15T14:25:10","guid":{"rendered":"https:\/\/zockun.com.br\/?p=2341"},"modified":"2026-07-15T11:25:10","modified_gmt":"2026-07-15T14:25:10","slug":"imposto-seletivo-como-a-indefinicao-das-aliquotas-compromete-o-planejamento-empresarial","status":"publish","type":"post","link":"https:\/\/zockun.com.br\/en\/imposto-seletivo-como-a-indefinicao-das-aliquotas-compromete-o-planejamento-empresarial\/","title":{"rendered":"(PT) Imposto Seletivo:  Como a indefini\u00e7\u00e3o das al\u00edquotas compromete o planejamento empresarial"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\">Sorry, this entry is only available in <a href=\"https:\/\/zockun.com.br\/pb\/wp-json\/wp\/v2\/posts\/2341\" class=\"qtranxs-available-language-link qtranxs-available-language-link-pb\" title=\"PT\">PT<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sorry, this entry is only available in PT.<\/p>\n","protected":false},"author":2,"featured_media":2259,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"class_list":["post-2341","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>(PT) Imposto Seletivo: Como a indefini\u00e7\u00e3o das al\u00edquotas compromete o planejamento empresarial  - Zockun e Fleury Advogados<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zockun.com.br\/en\/imposto-seletivo-como-a-indefinicao-das-aliquotas-compromete-o-planejamento-empresarial\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"(PT) Imposto Seletivo: Como a indefini\u00e7\u00e3o das al\u00edquotas compromete o planejamento empresarial  - Zockun e Fleury Advogados\" \/>\n<meta property=\"og:description\" content=\"Sorry, this entry is only available in PT.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zockun.com.br\/en\/imposto-seletivo-como-a-indefinicao-das-aliquotas-compromete-o-planejamento-empresarial\/\" \/>\n<meta property=\"og:site_name\" content=\"Zockun e Fleury Advogados\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/zockunadvogados\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-15T14:25:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zockun.com.br\/wp-content\/uploads\/2026\/05\/Foto-9-08-1024x576.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maur\u00edcio Zockun\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maur\u00edcio Zockun\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/zockun.com.br\\\/imposto-seletivo-como-a-indefinicao-das-aliquotas-compromete-o-planejamento-empresarial\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/imposto-seletivo-como-a-indefinicao-das-aliquotas-compromete-o-planejamento-empresarial\\\/\"},\"author\":{\"name\":\"Maur\u00edcio Zockun\",\"@id\":\"https:\\\/\\\/zockun.com.br\\\/#\\\/schema\\\/person\\\/789592191ab7fafbd84bfa0643f38064\"},\"headline\":\"(PT) Imposto Seletivo: Como a indefini\u00e7\u00e3o das al\u00edquotas compromete o planejamento empresarial\",\"datePublished\":\"2026-07-15T14:25:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/imposto-seletivo-como-a-indefinicao-das-aliquotas-compromete-o-planejamento-empresarial\\\/\"},\"wordCount\":764,\"publisher\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/imposto-seletivo-como-a-indefinicao-das-aliquotas-compromete-o-planejamento-empresarial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zockun.com.br\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Foto-9-08-scaled.png\",\"articleSection\":[\"Sem categoria\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/imposto-seletivo-como-a-indefinicao-das-aliquotas-compromete-o-planejamento-empresarial\\\/\",\"url\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/imposto-seletivo-como-a-indefinicao-das-aliquotas-compromete-o-planejamento-empresarial\\\/\",\"name\":\"(PT) Imposto Seletivo: Como a indefini\u00e7\u00e3o das al\u00edquotas compromete o planejamento empresarial  - Zockun e Fleury Advogados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/imposto-seletivo-como-a-indefinicao-das-aliquotas-compromete-o-planejamento-empresarial\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/imposto-seletivo-como-a-indefinicao-das-aliquotas-compromete-o-planejamento-empresarial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zockun.com.br\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Foto-9-08-scaled.png\",\"datePublished\":\"2026-07-15T14:25:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/imposto-seletivo-como-a-indefinicao-das-aliquotas-compromete-o-planejamento-empresarial\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/zockun.com.br\\\/en\\\/imposto-seletivo-como-a-indefinicao-das-aliquotas-compromete-o-planejamento-empresarial\\\/\"]]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/imposto-seletivo-como-a-indefinicao-das-aliquotas-compromete-o-planejamento-empresarial\\\/#primaryimage\",\"url\":\"https:\\\/\\\/zockun.com.br\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Foto-9-08-scaled.png\",\"contentUrl\":\"https:\\\/\\\/zockun.com.br\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Foto-9-08-scaled.png\",\"width\":2560,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/imposto-seletivo-como-a-indefinicao-das-aliquotas-compromete-o-planejamento-empresarial\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Imposto Seletivo: Como a indefini\u00e7\u00e3o das al\u00edquotas compromete o planejamento empresarial\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/\",\"name\":\"Zockun e Fleury Advogados\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/#organization\",\"name\":\"Zockun e Fleury Advogados\",\"url\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/zockun.com.br\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Favicon.jpg\",\"contentUrl\":\"https:\\\/\\\/zockun.com.br\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Favicon.jpg\",\"width\":400,\"height\":400,\"caption\":\"Zockun e Fleury Advogados\"},\"image\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/zockunadvogados\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/zockun-advogados\",\"https:\\\/\\\/www.instagram.com\\\/zockunefleury\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/zockun.com.br\\\/#\\\/schema\\\/person\\\/789592191ab7fafbd84bfa0643f38064\",\"name\":\"Maur\u00edcio Zockun\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bbb998b911e507fabd68e315a38f14aa6a6886dc41eb29d1f424ffb50e713f5c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bbb998b911e507fabd68e315a38f14aa6a6886dc41eb29d1f424ffb50e713f5c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bbb998b911e507fabd68e315a38f14aa6a6886dc41eb29d1f424ffb50e713f5c?s=96&d=mm&r=g\",\"caption\":\"Maur\u00edcio Zockun\"},\"url\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/author\\\/zockun\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"(PT) Imposto Seletivo: Como a indefini\u00e7\u00e3o das al\u00edquotas compromete o planejamento empresarial  - Zockun e Fleury Advogados","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zockun.com.br\/en\/imposto-seletivo-como-a-indefinicao-das-aliquotas-compromete-o-planejamento-empresarial\/","og_locale":"en_US","og_type":"article","og_title":"(PT) Imposto Seletivo: Como a indefini\u00e7\u00e3o das al\u00edquotas compromete o planejamento empresarial  - Zockun e Fleury Advogados","og_description":"Sorry, this entry is only available in PT.","og_url":"https:\/\/zockun.com.br\/en\/imposto-seletivo-como-a-indefinicao-das-aliquotas-compromete-o-planejamento-empresarial\/","og_site_name":"Zockun e Fleury Advogados","article_publisher":"https:\/\/www.facebook.com\/zockunadvogados","article_published_time":"2026-07-15T14:25:10+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/zockun.com.br\/wp-content\/uploads\/2026\/05\/Foto-9-08-1024x576.png","type":"image\/png"}],"author":"Maur\u00edcio Zockun","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Maur\u00edcio Zockun","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/zockun.com.br\/imposto-seletivo-como-a-indefinicao-das-aliquotas-compromete-o-planejamento-empresarial\/#article","isPartOf":{"@id":"https:\/\/zockun.com.br\/imposto-seletivo-como-a-indefinicao-das-aliquotas-compromete-o-planejamento-empresarial\/"},"author":{"name":"Maur\u00edcio Zockun","@id":"https:\/\/zockun.com.br\/#\/schema\/person\/789592191ab7fafbd84bfa0643f38064"},"headline":"(PT) Imposto Seletivo: Como a indefini\u00e7\u00e3o das al\u00edquotas compromete o planejamento empresarial","datePublished":"2026-07-15T14:25:10+00:00","mainEntityOfPage":{"@id":"https:\/\/zockun.com.br\/imposto-seletivo-como-a-indefinicao-das-aliquotas-compromete-o-planejamento-empresarial\/"},"wordCount":764,"publisher":{"@id":"https:\/\/zockun.com.br\/#organization"},"image":{"@id":"https:\/\/zockun.com.br\/imposto-seletivo-como-a-indefinicao-das-aliquotas-compromete-o-planejamento-empresarial\/#primaryimage"},"thumbnailUrl":"https:\/\/zockun.com.br\/wp-content\/uploads\/2026\/05\/Foto-9-08-scaled.png","articleSection":["Sem categoria"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/zockun.com.br\/en\/imposto-seletivo-como-a-indefinicao-das-aliquotas-compromete-o-planejamento-empresarial\/","url":"https:\/\/zockun.com.br\/en\/imposto-seletivo-como-a-indefinicao-das-aliquotas-compromete-o-planejamento-empresarial\/","name":"(PT) Imposto Seletivo: Como a indefini\u00e7\u00e3o das al\u00edquotas compromete o planejamento empresarial  - Zockun e Fleury Advogados","isPartOf":{"@id":"https:\/\/zockun.com.br\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/zockun.com.br\/en\/imposto-seletivo-como-a-indefinicao-das-aliquotas-compromete-o-planejamento-empresarial\/#primaryimage"},"image":{"@id":"https:\/\/zockun.com.br\/imposto-seletivo-como-a-indefinicao-das-aliquotas-compromete-o-planejamento-empresarial\/#primaryimage"},"thumbnailUrl":"https:\/\/zockun.com.br\/wp-content\/uploads\/2026\/05\/Foto-9-08-scaled.png","datePublished":"2026-07-15T14:25:10+00:00","breadcrumb":{"@id":"https:\/\/zockun.com.br\/en\/imposto-seletivo-como-a-indefinicao-das-aliquotas-compromete-o-planejamento-empresarial\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/zockun.com.br\/en\/imposto-seletivo-como-a-indefinicao-das-aliquotas-compromete-o-planejamento-empresarial\/"]]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/zockun.com.br\/en\/imposto-seletivo-como-a-indefinicao-das-aliquotas-compromete-o-planejamento-empresarial\/#primaryimage","url":"https:\/\/zockun.com.br\/wp-content\/uploads\/2026\/05\/Foto-9-08-scaled.png","contentUrl":"https:\/\/zockun.com.br\/wp-content\/uploads\/2026\/05\/Foto-9-08-scaled.png","width":2560,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/zockun.com.br\/en\/imposto-seletivo-como-a-indefinicao-das-aliquotas-compromete-o-planejamento-empresarial\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/zockun.com.br\/en\/"},{"@type":"ListItem","position":2,"name":"Imposto Seletivo: Como a indefini\u00e7\u00e3o das al\u00edquotas compromete o planejamento empresarial"}]},{"@type":"WebSite","@id":"https:\/\/zockun.com.br\/en\/#website","url":"https:\/\/zockun.com.br\/en\/","name":"Zockun e Fleury Advogados","description":"","publisher":{"@id":"https:\/\/zockun.com.br\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zockun.com.br\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/zockun.com.br\/en\/#organization","name":"Zockun e Fleury Advogados","url":"https:\/\/zockun.com.br\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/zockun.com.br\/en\/#\/schema\/logo\/image\/","url":"https:\/\/zockun.com.br\/wp-content\/uploads\/2025\/10\/Favicon.jpg","contentUrl":"https:\/\/zockun.com.br\/wp-content\/uploads\/2025\/10\/Favicon.jpg","width":400,"height":400,"caption":"Zockun e Fleury Advogados"},"image":{"@id":"https:\/\/zockun.com.br\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/zockunadvogados","https:\/\/www.linkedin.com\/company\/zockun-advogados","https:\/\/www.instagram.com\/zockunefleury\/"]},{"@type":"Person","@id":"https:\/\/zockun.com.br\/#\/schema\/person\/789592191ab7fafbd84bfa0643f38064","name":"Maur\u00edcio Zockun","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/bbb998b911e507fabd68e315a38f14aa6a6886dc41eb29d1f424ffb50e713f5c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bbb998b911e507fabd68e315a38f14aa6a6886dc41eb29d1f424ffb50e713f5c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bbb998b911e507fabd68e315a38f14aa6a6886dc41eb29d1f424ffb50e713f5c?s=96&d=mm&r=g","caption":"Maur\u00edcio Zockun"},"url":"https:\/\/zockun.com.br\/en\/author\/zockun\/"}]}},"_links":{"self":[{"href":"https:\/\/zockun.com.br\/en\/wp-json\/wp\/v2\/posts\/2341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zockun.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zockun.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zockun.com.br\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/zockun.com.br\/en\/wp-json\/wp\/v2\/comments?post=2341"}],"version-history":[{"count":3,"href":"https:\/\/zockun.com.br\/en\/wp-json\/wp\/v2\/posts\/2341\/revisions"}],"predecessor-version":[{"id":2344,"href":"https:\/\/zockun.com.br\/en\/wp-json\/wp\/v2\/posts\/2341\/revisions\/2344"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zockun.com.br\/en\/wp-json\/wp\/v2\/media\/2259"}],"wp:attachment":[{"href":"https:\/\/zockun.com.br\/en\/wp-json\/wp\/v2\/media?parent=2341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zockun.com.br\/en\/wp-json\/wp\/v2\/categories?post=2341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}