{"id":2068,"date":"2024-06-17T19:54:06","date_gmt":"2024-06-17T22:54:06","guid":{"rendered":"https:\/\/www.zockun.com.br\/?p=2068"},"modified":"2024-06-17T19:54:06","modified_gmt":"2024-06-17T22:54:06","slug":"decreto-paulista-institui-o-programa-integra-residuos-para-atender-as-necessidades-regionais-e-locais-de-manejo-de-residuos-solidos-urbanos","status":"publish","type":"post","link":"https:\/\/zockun.com.br\/en\/decreto-paulista-institui-o-programa-integra-residuos-para-atender-as-necessidades-regionais-e-locais-de-manejo-de-residuos-solidos-urbanos\/","title":{"rendered":"Decreto paulista institui o Programa Integra Res\u00edduos para atender \u00e0s necessidades regionais e locais de manejo de res\u00edduos s\u00f3lidos urbanos"},"content":{"rendered":"<p style=\"text-align: justify; text-indent: 35.45pt; line-height: 150%; margin: 6.0pt 0cm 6.0pt 0cm;\"><span style=\"font-size: 11.0pt; line-height: 150%; font-family: 'Georgia',serif;\">O Decreto estadual n\u00b0 68.578\/2024, publicado em 6 de junho de 2024, instituiu o Programa Integra Res\u00edduos no Estado de S\u00e3o Paulo. Esta iniciativa pretende garantir a disposi\u00e7\u00e3o final ambientalmente adequada dos rejeitos, promovendo projetos que sejam sustent\u00e1veis sob os aspectos econ\u00f4mico, social e ambiental.<\/span><\/p>\n<p style=\"text-align: justify; text-indent: 35.45pt; line-height: 150%; margin: 6.0pt 0cm 6.0pt 0cm;\"><span style=\"font-size: 11.0pt; line-height: 150%; font-family: 'Georgia',serif;\">Os objetivos do Programa incluem viabilizar a regionaliza\u00e7\u00e3o e gest\u00e3o integrada dos res\u00edduos s\u00f3lidos gerados nos munic\u00edpios paulistas, al\u00e9m de fornecer apoio t\u00e9cnico aos munic\u00edpios interessados em aderir \u00e0 regionaliza\u00e7\u00e3o, estimulando avan\u00e7os tecnol\u00f3gicos e de escala na presta\u00e7\u00e3o dos servi\u00e7os.<\/span><\/p>\n<p style=\"text-align: justify; text-indent: 35.45pt; line-height: 150%; margin: 6.0pt 0cm 6.0pt 0cm;\"><span style=\"font-size: 11.0pt; line-height: 150%; font-family: 'Georgia',serif;\">Dentre as atividades de apoio t\u00e9cnico que ser\u00e3o prestadas pelo Estado de S\u00e3o Paulo aos munic\u00edpios e unidades regionalizadas, destacam-se a avalia\u00e7\u00e3o da estrutura de governan\u00e7a necess\u00e1ria para implementa\u00e7\u00e3o do projeto, bem como a regula\u00e7\u00e3o contratual e mapeamento de potenciais investidores para a oferta dos servi\u00e7os.<\/span><\/p>\n<p style=\"text-align: justify; text-indent: 35.45pt; line-height: 150%; margin: 6.0pt 0cm 6.0pt 0cm;\"><span style=\"font-size: 11.0pt; line-height: 150%; font-family: 'Georgia',serif;\">Para a execu\u00e7\u00e3o dos objetivos pretendidos pelo Programa Integra Res\u00edduos, poder\u00e3o celebrados contratos, conv\u00eanios e parcerias, proporcionando in\u00fameras oportunidades de neg\u00f3cio para as empresas que atuam nesse ramo.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Decreto estadual n\u00b0 68.578\/2024, publicado em 6 de junho de 2024, instituiu o Programa Integra Res\u00edduos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2257,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[8],"class_list":["post-2068","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Decreto paulista institui o Programa Integra Res\u00edduos para atender \u00e0s necessidades regionais e locais de manejo de res\u00edduos s\u00f3lidos urbanos - Zockun e Fleury Advogados<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zockun.com.br\/en\/decreto-paulista-institui-o-programa-integra-residuos-para-atender-as-necessidades-regionais-e-locais-de-manejo-de-residuos-solidos-urbanos\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Decreto paulista institui o Programa Integra Res\u00edduos para atender \u00e0s necessidades regionais e locais de manejo de res\u00edduos s\u00f3lidos urbanos - Zockun e Fleury Advogados\" \/>\n<meta property=\"og:description\" content=\"O Decreto estadual n\u00b0 68.578\/2024, publicado em 6 de junho de 2024, instituiu o Programa Integra Res\u00edduos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zockun.com.br\/en\/decreto-paulista-institui-o-programa-integra-residuos-para-atender-as-necessidades-regionais-e-locais-de-manejo-de-residuos-solidos-urbanos\/\" \/>\n<meta property=\"og:site_name\" content=\"Zockun e Fleury Advogados\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/zockunadvogados\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-17T22:54:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zockun.com.br\/wp-content\/uploads\/2026\/05\/Foto-9-06-1024x576.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/zockun.com.br\\\/decreto-paulista-institui-o-programa-integra-residuos-para-atender-as-necessidades-regionais-e-locais-de-manejo-de-residuos-solidos-urbanos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/decreto-paulista-institui-o-programa-integra-residuos-para-atender-as-necessidades-regionais-e-locais-de-manejo-de-residuos-solidos-urbanos\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/zockun.com.br\\\/#\\\/schema\\\/person\\\/7b2361a745fbc8b220437ab210761a33\"},\"headline\":\"Decreto paulista institui o Programa Integra Res\u00edduos para atender \u00e0s necessidades regionais e locais de manejo de res\u00edduos s\u00f3lidos urbanos\",\"datePublished\":\"2024-06-17T22:54:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/decreto-paulista-institui-o-programa-integra-residuos-para-atender-as-necessidades-regionais-e-locais-de-manejo-de-residuos-solidos-urbanos\\\/\"},\"wordCount\":212,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/decreto-paulista-institui-o-programa-integra-residuos-para-atender-as-necessidades-regionais-e-locais-de-manejo-de-residuos-solidos-urbanos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zockun.com.br\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Foto-9-06-scaled.png\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/zockun.com.br\\\/decreto-paulista-institui-o-programa-integra-residuos-para-atender-as-necessidades-regionais-e-locais-de-manejo-de-residuos-solidos-urbanos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/decreto-paulista-institui-o-programa-integra-residuos-para-atender-as-necessidades-regionais-e-locais-de-manejo-de-residuos-solidos-urbanos\\\/\",\"url\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/decreto-paulista-institui-o-programa-integra-residuos-para-atender-as-necessidades-regionais-e-locais-de-manejo-de-residuos-solidos-urbanos\\\/\",\"name\":\"Decreto paulista institui o Programa Integra Res\u00edduos para atender \u00e0s necessidades regionais e locais de manejo de res\u00edduos s\u00f3lidos urbanos - Zockun e Fleury Advogados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/decreto-paulista-institui-o-programa-integra-residuos-para-atender-as-necessidades-regionais-e-locais-de-manejo-de-residuos-solidos-urbanos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/decreto-paulista-institui-o-programa-integra-residuos-para-atender-as-necessidades-regionais-e-locais-de-manejo-de-residuos-solidos-urbanos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zockun.com.br\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Foto-9-06-scaled.png\",\"datePublished\":\"2024-06-17T22:54:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/decreto-paulista-institui-o-programa-integra-residuos-para-atender-as-necessidades-regionais-e-locais-de-manejo-de-residuos-solidos-urbanos\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/zockun.com.br\\\/en\\\/decreto-paulista-institui-o-programa-integra-residuos-para-atender-as-necessidades-regionais-e-locais-de-manejo-de-residuos-solidos-urbanos\\\/\"]]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/decreto-paulista-institui-o-programa-integra-residuos-para-atender-as-necessidades-regionais-e-locais-de-manejo-de-residuos-solidos-urbanos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/zockun.com.br\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Foto-9-06-scaled.png\",\"contentUrl\":\"https:\\\/\\\/zockun.com.br\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Foto-9-06-scaled.png\",\"width\":2560,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/decreto-paulista-institui-o-programa-integra-residuos-para-atender-as-necessidades-regionais-e-locais-de-manejo-de-residuos-solidos-urbanos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Decreto paulista institui o Programa Integra Res\u00edduos para atender \u00e0s necessidades regionais e locais de manejo de res\u00edduos s\u00f3lidos urbanos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/\",\"name\":\"Zockun e Fleury Advogados\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/#organization\",\"name\":\"Zockun e Fleury Advogados\",\"url\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/zockun.com.br\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Favicon.jpg\",\"contentUrl\":\"https:\\\/\\\/zockun.com.br\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Favicon.jpg\",\"width\":400,\"height\":400,\"caption\":\"Zockun e Fleury Advogados\"},\"image\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/zockunadvogados\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/zockun-advogados\",\"https:\\\/\\\/www.instagram.com\\\/zockunefleury\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/zockun.com.br\\\/#\\\/schema\\\/person\\\/7b2361a745fbc8b220437ab210761a33\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/zockun.com.br\"],\"url\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Decreto paulista institui o Programa Integra Res\u00edduos para atender \u00e0s necessidades regionais e locais de manejo de res\u00edduos s\u00f3lidos urbanos - Zockun e Fleury Advogados","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zockun.com.br\/en\/decreto-paulista-institui-o-programa-integra-residuos-para-atender-as-necessidades-regionais-e-locais-de-manejo-de-residuos-solidos-urbanos\/","og_locale":"en_US","og_type":"article","og_title":"Decreto paulista institui o Programa Integra Res\u00edduos para atender \u00e0s necessidades regionais e locais de manejo de res\u00edduos s\u00f3lidos urbanos - Zockun e Fleury Advogados","og_description":"O Decreto estadual n\u00b0 68.578\/2024, publicado em 6 de junho de 2024, instituiu o Programa Integra Res\u00edduos [&hellip;]","og_url":"https:\/\/zockun.com.br\/en\/decreto-paulista-institui-o-programa-integra-residuos-para-atender-as-necessidades-regionais-e-locais-de-manejo-de-residuos-solidos-urbanos\/","og_site_name":"Zockun e Fleury Advogados","article_publisher":"https:\/\/www.facebook.com\/zockunadvogados","article_published_time":"2024-06-17T22:54:06+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/zockun.com.br\/wp-content\/uploads\/2026\/05\/Foto-9-06-1024x576.png","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/zockun.com.br\/decreto-paulista-institui-o-programa-integra-residuos-para-atender-as-necessidades-regionais-e-locais-de-manejo-de-residuos-solidos-urbanos\/#article","isPartOf":{"@id":"https:\/\/zockun.com.br\/decreto-paulista-institui-o-programa-integra-residuos-para-atender-as-necessidades-regionais-e-locais-de-manejo-de-residuos-solidos-urbanos\/"},"author":{"name":"admin","@id":"https:\/\/zockun.com.br\/#\/schema\/person\/7b2361a745fbc8b220437ab210761a33"},"headline":"Decreto paulista institui o Programa Integra Res\u00edduos para atender \u00e0s necessidades regionais e locais de manejo de res\u00edduos s\u00f3lidos urbanos","datePublished":"2024-06-17T22:54:06+00:00","mainEntityOfPage":{"@id":"https:\/\/zockun.com.br\/decreto-paulista-institui-o-programa-integra-residuos-para-atender-as-necessidades-regionais-e-locais-de-manejo-de-residuos-solidos-urbanos\/"},"wordCount":212,"commentCount":0,"publisher":{"@id":"https:\/\/zockun.com.br\/#organization"},"image":{"@id":"https:\/\/zockun.com.br\/decreto-paulista-institui-o-programa-integra-residuos-para-atender-as-necessidades-regionais-e-locais-de-manejo-de-residuos-solidos-urbanos\/#primaryimage"},"thumbnailUrl":"https:\/\/zockun.com.br\/wp-content\/uploads\/2026\/05\/Foto-9-06-scaled.png","articleSection":["Not\u00edcias"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/zockun.com.br\/decreto-paulista-institui-o-programa-integra-residuos-para-atender-as-necessidades-regionais-e-locais-de-manejo-de-residuos-solidos-urbanos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/zockun.com.br\/en\/decreto-paulista-institui-o-programa-integra-residuos-para-atender-as-necessidades-regionais-e-locais-de-manejo-de-residuos-solidos-urbanos\/","url":"https:\/\/zockun.com.br\/en\/decreto-paulista-institui-o-programa-integra-residuos-para-atender-as-necessidades-regionais-e-locais-de-manejo-de-residuos-solidos-urbanos\/","name":"Decreto paulista institui o Programa Integra Res\u00edduos para atender \u00e0s necessidades regionais e locais de manejo de res\u00edduos s\u00f3lidos urbanos - Zockun e Fleury Advogados","isPartOf":{"@id":"https:\/\/zockun.com.br\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/zockun.com.br\/en\/decreto-paulista-institui-o-programa-integra-residuos-para-atender-as-necessidades-regionais-e-locais-de-manejo-de-residuos-solidos-urbanos\/#primaryimage"},"image":{"@id":"https:\/\/zockun.com.br\/decreto-paulista-institui-o-programa-integra-residuos-para-atender-as-necessidades-regionais-e-locais-de-manejo-de-residuos-solidos-urbanos\/#primaryimage"},"thumbnailUrl":"https:\/\/zockun.com.br\/wp-content\/uploads\/2026\/05\/Foto-9-06-scaled.png","datePublished":"2024-06-17T22:54:06+00:00","breadcrumb":{"@id":"https:\/\/zockun.com.br\/en\/decreto-paulista-institui-o-programa-integra-residuos-para-atender-as-necessidades-regionais-e-locais-de-manejo-de-residuos-solidos-urbanos\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/zockun.com.br\/en\/decreto-paulista-institui-o-programa-integra-residuos-para-atender-as-necessidades-regionais-e-locais-de-manejo-de-residuos-solidos-urbanos\/"]]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/zockun.com.br\/en\/decreto-paulista-institui-o-programa-integra-residuos-para-atender-as-necessidades-regionais-e-locais-de-manejo-de-residuos-solidos-urbanos\/#primaryimage","url":"https:\/\/zockun.com.br\/wp-content\/uploads\/2026\/05\/Foto-9-06-scaled.png","contentUrl":"https:\/\/zockun.com.br\/wp-content\/uploads\/2026\/05\/Foto-9-06-scaled.png","width":2560,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/zockun.com.br\/en\/decreto-paulista-institui-o-programa-integra-residuos-para-atender-as-necessidades-regionais-e-locais-de-manejo-de-residuos-solidos-urbanos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/zockun.com.br\/en\/"},{"@type":"ListItem","position":2,"name":"Decreto paulista institui o Programa Integra Res\u00edduos para atender \u00e0s necessidades regionais e locais de manejo de res\u00edduos s\u00f3lidos urbanos"}]},{"@type":"WebSite","@id":"https:\/\/zockun.com.br\/en\/#website","url":"https:\/\/zockun.com.br\/en\/","name":"Zockun e Fleury Advogados","description":"","publisher":{"@id":"https:\/\/zockun.com.br\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zockun.com.br\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/zockun.com.br\/en\/#organization","name":"Zockun e Fleury Advogados","url":"https:\/\/zockun.com.br\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/zockun.com.br\/en\/#\/schema\/logo\/image\/","url":"https:\/\/zockun.com.br\/wp-content\/uploads\/2025\/10\/Favicon.jpg","contentUrl":"https:\/\/zockun.com.br\/wp-content\/uploads\/2025\/10\/Favicon.jpg","width":400,"height":400,"caption":"Zockun e Fleury Advogados"},"image":{"@id":"https:\/\/zockun.com.br\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/zockunadvogados","https:\/\/www.linkedin.com\/company\/zockun-advogados","https:\/\/www.instagram.com\/zockunefleury\/"]},{"@type":"Person","@id":"https:\/\/zockun.com.br\/#\/schema\/person\/7b2361a745fbc8b220437ab210761a33","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/zockun.com.br"],"url":"https:\/\/zockun.com.br\/en\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/zockun.com.br\/en\/wp-json\/wp\/v2\/posts\/2068","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zockun.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zockun.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zockun.com.br\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zockun.com.br\/en\/wp-json\/wp\/v2\/comments?post=2068"}],"version-history":[{"count":0,"href":"https:\/\/zockun.com.br\/en\/wp-json\/wp\/v2\/posts\/2068\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zockun.com.br\/en\/wp-json\/wp\/v2\/media\/2257"}],"wp:attachment":[{"href":"https:\/\/zockun.com.br\/en\/wp-json\/wp\/v2\/media?parent=2068"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zockun.com.br\/en\/wp-json\/wp\/v2\/categories?post=2068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}