{"id":1962,"date":"2024-02-28T14:37:56","date_gmt":"2024-02-28T17:37:56","guid":{"rendered":"https:\/\/www.zockun.com.br\/?p=1962"},"modified":"2024-02-28T14:37:56","modified_gmt":"2024-02-28T17:37:56","slug":"lancamento-37a-edicao-da-obra-curso-de-direito-administrativo","status":"publish","type":"post","link":"https:\/\/zockun.com.br\/en\/lancamento-37a-edicao-da-obra-curso-de-direito-administrativo\/","title":{"rendered":"Lan\u00e7amento: 37\u00aa edi\u00e7\u00e3o da obra &#8220;Curso de Direito Administrativo&#8221;"},"content":{"rendered":"<p>Est\u00e1 dispon\u00edvel para pr\u00e9-venda o lan\u00e7amento especial da 37\u00aa edi\u00e7\u00e3o do Curso de Direito Administrativo, de Celso Ant\u00f4nio Bandeira de Mello. A nova produ\u00e7\u00e3o foi realizada em coautoria pelos professores de Direito Administrativo na Pontif\u00edcia Universidade Cat\u00f3lica de S\u00e3o Paulo (PUC-SP), Weida Zancaner, Carolina Zancaner Zockun, e nosso s\u00f3cio, <a href=\"https:\/\/www.linkedin.com\/in\/ACoAAAW9avQByLHn9mfWuTkI6x0_Mzf0ZF9QjjA\" data-attribute-index=\"4\" data-entity-type=\"MINI_PROFILE\">Maur\u00edcio Zockun<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<p>Publicada pela Editora F\u00d3RUM, a obra traz adapta\u00e7\u00f5es, atualiza\u00e7\u00f5es e aprimoramentos significativos, com destaque nos Cap\u00edtulos IX e X, que abordam os temas de licita\u00e7\u00e3o e contrata\u00e7\u00e3o p\u00fablica.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/loja.editoraforum.com.br\/curso-de-direito-administrativo\">Acesse aqui<\/a> para realizar a compra do curso.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.zockun.com.br\/_2018\/wp-content\/uploads\/2024\/02\/Livro_ajustado.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-1964 aligncenter\" src=\"http:\/\/www.zockun.com.br\/_2018\/wp-content\/uploads\/2024\/02\/Livro_ajustado.jpg\" alt=\"\" width=\"387\" height=\"387\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Est\u00e1 dispon\u00edvel para pr\u00e9-venda o lan\u00e7amento especial da 37\u00aa edi\u00e7\u00e3o do Curso de Direito Administrativo, de Celso [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2259,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[8,7],"class_list":["post-1962","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-publicacoes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lan\u00e7amento: 37\u00aa edi\u00e7\u00e3o da obra &quot;Curso de Direito Administrativo&quot; - Zockun e Fleury Advogados<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zockun.com.br\/en\/lancamento-37a-edicao-da-obra-curso-de-direito-administrativo\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lan\u00e7amento: 37\u00aa edi\u00e7\u00e3o da obra &quot;Curso de Direito Administrativo&quot; - Zockun e Fleury Advogados\" \/>\n<meta property=\"og:description\" content=\"Est\u00e1 dispon\u00edvel para pr\u00e9-venda o lan\u00e7amento especial da 37\u00aa edi\u00e7\u00e3o do Curso de Direito Administrativo, de Celso [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zockun.com.br\/en\/lancamento-37a-edicao-da-obra-curso-de-direito-administrativo\/\" \/>\n<meta property=\"og:site_name\" content=\"Zockun e Fleury Advogados\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/zockunadvogados\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-28T17:37:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zockun.com.br\/wp-content\/uploads\/2026\/05\/Foto-9-08-1024x576.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/zockun.com.br\\\/lancamento-37a-edicao-da-obra-curso-de-direito-administrativo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/lancamento-37a-edicao-da-obra-curso-de-direito-administrativo\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/zockun.com.br\\\/#\\\/schema\\\/person\\\/7b2361a745fbc8b220437ab210761a33\"},\"headline\":\"Lan\u00e7amento: 37\u00aa edi\u00e7\u00e3o da obra &#8220;Curso de Direito Administrativo&#8221;\",\"datePublished\":\"2024-02-28T17:37:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/lancamento-37a-edicao-da-obra-curso-de-direito-administrativo\\\/\"},\"wordCount\":118,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/lancamento-37a-edicao-da-obra-curso-de-direito-administrativo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zockun.com.br\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Foto-9-08-scaled.png\",\"articleSection\":[\"Not\u00edcias\",\"Publica\u00e7\u00f5es\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/zockun.com.br\\\/lancamento-37a-edicao-da-obra-curso-de-direito-administrativo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/lancamento-37a-edicao-da-obra-curso-de-direito-administrativo\\\/\",\"url\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/lancamento-37a-edicao-da-obra-curso-de-direito-administrativo\\\/\",\"name\":\"Lan\u00e7amento: 37\u00aa edi\u00e7\u00e3o da obra \\\"Curso de Direito Administrativo\\\" - Zockun e Fleury Advogados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/lancamento-37a-edicao-da-obra-curso-de-direito-administrativo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/lancamento-37a-edicao-da-obra-curso-de-direito-administrativo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zockun.com.br\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Foto-9-08-scaled.png\",\"datePublished\":\"2024-02-28T17:37:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/lancamento-37a-edicao-da-obra-curso-de-direito-administrativo\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/zockun.com.br\\\/en\\\/lancamento-37a-edicao-da-obra-curso-de-direito-administrativo\\\/\"]]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/lancamento-37a-edicao-da-obra-curso-de-direito-administrativo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/zockun.com.br\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Foto-9-08-scaled.png\",\"contentUrl\":\"https:\\\/\\\/zockun.com.br\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Foto-9-08-scaled.png\",\"width\":2560,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/lancamento-37a-edicao-da-obra-curso-de-direito-administrativo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lan\u00e7amento: 37\u00aa edi\u00e7\u00e3o da obra &#8220;Curso de Direito Administrativo&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/\",\"name\":\"Zockun e Fleury Advogados\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/#organization\",\"name\":\"Zockun e Fleury Advogados\",\"url\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/zockun.com.br\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Favicon.jpg\",\"contentUrl\":\"https:\\\/\\\/zockun.com.br\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Favicon.jpg\",\"width\":400,\"height\":400,\"caption\":\"Zockun e Fleury Advogados\"},\"image\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/zockunadvogados\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/zockun-advogados\",\"https:\\\/\\\/www.instagram.com\\\/zockunefleury\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/zockun.com.br\\\/#\\\/schema\\\/person\\\/7b2361a745fbc8b220437ab210761a33\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/zockun.com.br\"],\"url\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lan\u00e7amento: 37\u00aa edi\u00e7\u00e3o da obra \"Curso de Direito Administrativo\" - Zockun e Fleury Advogados","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zockun.com.br\/en\/lancamento-37a-edicao-da-obra-curso-de-direito-administrativo\/","og_locale":"en_US","og_type":"article","og_title":"Lan\u00e7amento: 37\u00aa edi\u00e7\u00e3o da obra \"Curso de Direito Administrativo\" - Zockun e Fleury Advogados","og_description":"Est\u00e1 dispon\u00edvel para pr\u00e9-venda o lan\u00e7amento especial da 37\u00aa edi\u00e7\u00e3o do Curso de Direito Administrativo, de Celso [&hellip;]","og_url":"https:\/\/zockun.com.br\/en\/lancamento-37a-edicao-da-obra-curso-de-direito-administrativo\/","og_site_name":"Zockun e Fleury Advogados","article_publisher":"https:\/\/www.facebook.com\/zockunadvogados","article_published_time":"2024-02-28T17:37:56+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/zockun.com.br\/wp-content\/uploads\/2026\/05\/Foto-9-08-1024x576.png","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/zockun.com.br\/lancamento-37a-edicao-da-obra-curso-de-direito-administrativo\/#article","isPartOf":{"@id":"https:\/\/zockun.com.br\/lancamento-37a-edicao-da-obra-curso-de-direito-administrativo\/"},"author":{"name":"admin","@id":"https:\/\/zockun.com.br\/#\/schema\/person\/7b2361a745fbc8b220437ab210761a33"},"headline":"Lan\u00e7amento: 37\u00aa edi\u00e7\u00e3o da obra &#8220;Curso de Direito Administrativo&#8221;","datePublished":"2024-02-28T17:37:56+00:00","mainEntityOfPage":{"@id":"https:\/\/zockun.com.br\/lancamento-37a-edicao-da-obra-curso-de-direito-administrativo\/"},"wordCount":118,"commentCount":0,"publisher":{"@id":"https:\/\/zockun.com.br\/#organization"},"image":{"@id":"https:\/\/zockun.com.br\/lancamento-37a-edicao-da-obra-curso-de-direito-administrativo\/#primaryimage"},"thumbnailUrl":"https:\/\/zockun.com.br\/wp-content\/uploads\/2026\/05\/Foto-9-08-scaled.png","articleSection":["Not\u00edcias","Publica\u00e7\u00f5es"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/zockun.com.br\/lancamento-37a-edicao-da-obra-curso-de-direito-administrativo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/zockun.com.br\/en\/lancamento-37a-edicao-da-obra-curso-de-direito-administrativo\/","url":"https:\/\/zockun.com.br\/en\/lancamento-37a-edicao-da-obra-curso-de-direito-administrativo\/","name":"Lan\u00e7amento: 37\u00aa edi\u00e7\u00e3o da obra \"Curso de Direito Administrativo\" - Zockun e Fleury Advogados","isPartOf":{"@id":"https:\/\/zockun.com.br\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/zockun.com.br\/en\/lancamento-37a-edicao-da-obra-curso-de-direito-administrativo\/#primaryimage"},"image":{"@id":"https:\/\/zockun.com.br\/lancamento-37a-edicao-da-obra-curso-de-direito-administrativo\/#primaryimage"},"thumbnailUrl":"https:\/\/zockun.com.br\/wp-content\/uploads\/2026\/05\/Foto-9-08-scaled.png","datePublished":"2024-02-28T17:37:56+00:00","breadcrumb":{"@id":"https:\/\/zockun.com.br\/en\/lancamento-37a-edicao-da-obra-curso-de-direito-administrativo\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/zockun.com.br\/en\/lancamento-37a-edicao-da-obra-curso-de-direito-administrativo\/"]]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/zockun.com.br\/en\/lancamento-37a-edicao-da-obra-curso-de-direito-administrativo\/#primaryimage","url":"https:\/\/zockun.com.br\/wp-content\/uploads\/2026\/05\/Foto-9-08-scaled.png","contentUrl":"https:\/\/zockun.com.br\/wp-content\/uploads\/2026\/05\/Foto-9-08-scaled.png","width":2560,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/zockun.com.br\/en\/lancamento-37a-edicao-da-obra-curso-de-direito-administrativo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/zockun.com.br\/en\/"},{"@type":"ListItem","position":2,"name":"Lan\u00e7amento: 37\u00aa edi\u00e7\u00e3o da obra &#8220;Curso de Direito Administrativo&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/zockun.com.br\/en\/#website","url":"https:\/\/zockun.com.br\/en\/","name":"Zockun e Fleury Advogados","description":"","publisher":{"@id":"https:\/\/zockun.com.br\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zockun.com.br\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/zockun.com.br\/en\/#organization","name":"Zockun e Fleury Advogados","url":"https:\/\/zockun.com.br\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/zockun.com.br\/en\/#\/schema\/logo\/image\/","url":"https:\/\/zockun.com.br\/wp-content\/uploads\/2025\/10\/Favicon.jpg","contentUrl":"https:\/\/zockun.com.br\/wp-content\/uploads\/2025\/10\/Favicon.jpg","width":400,"height":400,"caption":"Zockun e Fleury Advogados"},"image":{"@id":"https:\/\/zockun.com.br\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/zockunadvogados","https:\/\/www.linkedin.com\/company\/zockun-advogados","https:\/\/www.instagram.com\/zockunefleury\/"]},{"@type":"Person","@id":"https:\/\/zockun.com.br\/#\/schema\/person\/7b2361a745fbc8b220437ab210761a33","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/zockun.com.br"],"url":"https:\/\/zockun.com.br\/en\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/zockun.com.br\/en\/wp-json\/wp\/v2\/posts\/1962","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zockun.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zockun.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zockun.com.br\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zockun.com.br\/en\/wp-json\/wp\/v2\/comments?post=1962"}],"version-history":[{"count":0,"href":"https:\/\/zockun.com.br\/en\/wp-json\/wp\/v2\/posts\/1962\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zockun.com.br\/en\/wp-json\/wp\/v2\/media\/2259"}],"wp:attachment":[{"href":"https:\/\/zockun.com.br\/en\/wp-json\/wp\/v2\/media?parent=1962"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zockun.com.br\/en\/wp-json\/wp\/v2\/categories?post=1962"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}