{"id":1341,"date":"2023-05-17T13:47:11","date_gmt":"2023-05-17T16:47:11","guid":{"rendered":"http:\/\/www.zockun.com.br\/?p=1341"},"modified":"2023-05-17T13:47:11","modified_gmt":"2023-05-17T16:47:11","slug":"stf-mantem-a-suspensao-das-decisoes-que-afastaram-a-majoracao-das-aliquotas-do-pis-e-da-cofins-sobre-receitas-financeiras","status":"publish","type":"post","link":"https:\/\/zockun.com.br\/en\/stf-mantem-a-suspensao-das-decisoes-que-afastaram-a-majoracao-das-aliquotas-do-pis-e-da-cofins-sobre-receitas-financeiras\/","title":{"rendered":"STF mant\u00e9m a suspens\u00e3o das decis\u00f5es que afastaram a majora\u00e7\u00e3o das al\u00edquotas do PIS e da COFINS sobre receitas financeiras"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>Em 9\/5\/2023 a liminar concedida pelo Ministro Ricardo Lewandowski nos autos da A\u00e7\u00e3o Declarat\u00f3ria de Constitucionalidade 84 foi levada ao referendo do plen\u00e1rio do Supremo Tribunal Federal.<\/p>\n<p>&nbsp;<\/p>\n<p>Por 9 votos a dois, a liminar concedida pelo Ministro Ricardo Lewandowski foi referendada. Segundo o ministro, \u201co Decreto 11.374\/2023 n\u00e3o pode ser equiparado a institui\u00e7\u00e3o ou aumento de tributo e, por isso, n\u00e3o viola os princ\u00edpios da seguran\u00e7a jur\u00eddica e da n\u00e3o surpresa, na medida em que o contribuinte j\u00e1 experimentava, desde 2015, a incid\u00eancia das al\u00edquotas de 0,65% e 4%\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Divergiram apenas o Ministro Andr\u00e9 Mendon\u00e7a e a Ministra Rosa Weber, que entenderam que a majora\u00e7\u00e3o promovida pelo referido decreto viola o princ\u00edpio da anterioridade.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Em 9\/5\/2023 a liminar concedida pelo Ministro Ricardo Lewandowski nos autos da A\u00e7\u00e3o Declarat\u00f3ria de Constitucionalidade [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2252,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[8],"class_list":["post-1341","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>STF mant\u00e9m a suspens\u00e3o das decis\u00f5es que afastaram a majora\u00e7\u00e3o das al\u00edquotas do PIS e da COFINS sobre receitas financeiras - Zockun e Fleury Advogados<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zockun.com.br\/en\/stf-mantem-a-suspensao-das-decisoes-que-afastaram-a-majoracao-das-aliquotas-do-pis-e-da-cofins-sobre-receitas-financeiras\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"STF mant\u00e9m a suspens\u00e3o das decis\u00f5es que afastaram a majora\u00e7\u00e3o das al\u00edquotas do PIS e da COFINS sobre receitas financeiras - Zockun e Fleury Advogados\" \/>\n<meta property=\"og:description\" content=\"&nbsp; Em 9\/5\/2023 a liminar concedida pelo Ministro Ricardo Lewandowski nos autos da A\u00e7\u00e3o Declarat\u00f3ria de Constitucionalidade [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zockun.com.br\/en\/stf-mantem-a-suspensao-das-decisoes-que-afastaram-a-majoracao-das-aliquotas-do-pis-e-da-cofins-sobre-receitas-financeiras\/\" \/>\n<meta property=\"og:site_name\" content=\"Zockun e Fleury Advogados\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/zockunadvogados\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-17T16:47:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zockun.com.br\/wp-content\/uploads\/2026\/05\/Foto-9-01-1-1024x576.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/zockun.com.br\\\/stf-mantem-a-suspensao-das-decisoes-que-afastaram-a-majoracao-das-aliquotas-do-pis-e-da-cofins-sobre-receitas-financeiras\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/stf-mantem-a-suspensao-das-decisoes-que-afastaram-a-majoracao-das-aliquotas-do-pis-e-da-cofins-sobre-receitas-financeiras\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/zockun.com.br\\\/#\\\/schema\\\/person\\\/7b2361a745fbc8b220437ab210761a33\"},\"headline\":\"STF mant\u00e9m a suspens\u00e3o das decis\u00f5es que afastaram a majora\u00e7\u00e3o das al\u00edquotas do PIS e da COFINS sobre receitas financeiras\",\"datePublished\":\"2023-05-17T16:47:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/stf-mantem-a-suspensao-das-decisoes-que-afastaram-a-majoracao-das-aliquotas-do-pis-e-da-cofins-sobre-receitas-financeiras\\\/\"},\"wordCount\":150,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/stf-mantem-a-suspensao-das-decisoes-que-afastaram-a-majoracao-das-aliquotas-do-pis-e-da-cofins-sobre-receitas-financeiras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zockun.com.br\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Foto-9-01-1-scaled.png\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/zockun.com.br\\\/stf-mantem-a-suspensao-das-decisoes-que-afastaram-a-majoracao-das-aliquotas-do-pis-e-da-cofins-sobre-receitas-financeiras\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/stf-mantem-a-suspensao-das-decisoes-que-afastaram-a-majoracao-das-aliquotas-do-pis-e-da-cofins-sobre-receitas-financeiras\\\/\",\"url\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/stf-mantem-a-suspensao-das-decisoes-que-afastaram-a-majoracao-das-aliquotas-do-pis-e-da-cofins-sobre-receitas-financeiras\\\/\",\"name\":\"STF mant\u00e9m a suspens\u00e3o das decis\u00f5es que afastaram a majora\u00e7\u00e3o das al\u00edquotas do PIS e da COFINS sobre receitas financeiras - Zockun e Fleury Advogados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/stf-mantem-a-suspensao-das-decisoes-que-afastaram-a-majoracao-das-aliquotas-do-pis-e-da-cofins-sobre-receitas-financeiras\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/stf-mantem-a-suspensao-das-decisoes-que-afastaram-a-majoracao-das-aliquotas-do-pis-e-da-cofins-sobre-receitas-financeiras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zockun.com.br\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Foto-9-01-1-scaled.png\",\"datePublished\":\"2023-05-17T16:47:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/stf-mantem-a-suspensao-das-decisoes-que-afastaram-a-majoracao-das-aliquotas-do-pis-e-da-cofins-sobre-receitas-financeiras\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/zockun.com.br\\\/en\\\/stf-mantem-a-suspensao-das-decisoes-que-afastaram-a-majoracao-das-aliquotas-do-pis-e-da-cofins-sobre-receitas-financeiras\\\/\"]]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/stf-mantem-a-suspensao-das-decisoes-que-afastaram-a-majoracao-das-aliquotas-do-pis-e-da-cofins-sobre-receitas-financeiras\\\/#primaryimage\",\"url\":\"https:\\\/\\\/zockun.com.br\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Foto-9-01-1-scaled.png\",\"contentUrl\":\"https:\\\/\\\/zockun.com.br\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Foto-9-01-1-scaled.png\",\"width\":2560,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/stf-mantem-a-suspensao-das-decisoes-que-afastaram-a-majoracao-das-aliquotas-do-pis-e-da-cofins-sobre-receitas-financeiras\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"STF mant\u00e9m a suspens\u00e3o das decis\u00f5es que afastaram a majora\u00e7\u00e3o das al\u00edquotas do PIS e da COFINS sobre receitas financeiras\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/\",\"name\":\"Zockun e Fleury Advogados\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/#organization\",\"name\":\"Zockun e Fleury Advogados\",\"url\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/zockun.com.br\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Favicon.jpg\",\"contentUrl\":\"https:\\\/\\\/zockun.com.br\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Favicon.jpg\",\"width\":400,\"height\":400,\"caption\":\"Zockun e Fleury Advogados\"},\"image\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/zockunadvogados\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/zockun-advogados\",\"https:\\\/\\\/www.instagram.com\\\/zockunefleury\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/zockun.com.br\\\/#\\\/schema\\\/person\\\/7b2361a745fbc8b220437ab210761a33\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/zockun.com.br\"],\"url\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"STF mant\u00e9m a suspens\u00e3o das decis\u00f5es que afastaram a majora\u00e7\u00e3o das al\u00edquotas do PIS e da COFINS sobre receitas financeiras - Zockun e Fleury Advogados","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zockun.com.br\/en\/stf-mantem-a-suspensao-das-decisoes-que-afastaram-a-majoracao-das-aliquotas-do-pis-e-da-cofins-sobre-receitas-financeiras\/","og_locale":"en_US","og_type":"article","og_title":"STF mant\u00e9m a suspens\u00e3o das decis\u00f5es que afastaram a majora\u00e7\u00e3o das al\u00edquotas do PIS e da COFINS sobre receitas financeiras - Zockun e Fleury Advogados","og_description":"&nbsp; Em 9\/5\/2023 a liminar concedida pelo Ministro Ricardo Lewandowski nos autos da A\u00e7\u00e3o Declarat\u00f3ria de Constitucionalidade [&hellip;]","og_url":"https:\/\/zockun.com.br\/en\/stf-mantem-a-suspensao-das-decisoes-que-afastaram-a-majoracao-das-aliquotas-do-pis-e-da-cofins-sobre-receitas-financeiras\/","og_site_name":"Zockun e Fleury Advogados","article_publisher":"https:\/\/www.facebook.com\/zockunadvogados","article_published_time":"2023-05-17T16:47:11+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/zockun.com.br\/wp-content\/uploads\/2026\/05\/Foto-9-01-1-1024x576.png","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/zockun.com.br\/stf-mantem-a-suspensao-das-decisoes-que-afastaram-a-majoracao-das-aliquotas-do-pis-e-da-cofins-sobre-receitas-financeiras\/#article","isPartOf":{"@id":"https:\/\/zockun.com.br\/stf-mantem-a-suspensao-das-decisoes-que-afastaram-a-majoracao-das-aliquotas-do-pis-e-da-cofins-sobre-receitas-financeiras\/"},"author":{"name":"admin","@id":"https:\/\/zockun.com.br\/#\/schema\/person\/7b2361a745fbc8b220437ab210761a33"},"headline":"STF mant\u00e9m a suspens\u00e3o das decis\u00f5es que afastaram a majora\u00e7\u00e3o das al\u00edquotas do PIS e da COFINS sobre receitas financeiras","datePublished":"2023-05-17T16:47:11+00:00","mainEntityOfPage":{"@id":"https:\/\/zockun.com.br\/stf-mantem-a-suspensao-das-decisoes-que-afastaram-a-majoracao-das-aliquotas-do-pis-e-da-cofins-sobre-receitas-financeiras\/"},"wordCount":150,"commentCount":0,"publisher":{"@id":"https:\/\/zockun.com.br\/#organization"},"image":{"@id":"https:\/\/zockun.com.br\/stf-mantem-a-suspensao-das-decisoes-que-afastaram-a-majoracao-das-aliquotas-do-pis-e-da-cofins-sobre-receitas-financeiras\/#primaryimage"},"thumbnailUrl":"https:\/\/zockun.com.br\/wp-content\/uploads\/2026\/05\/Foto-9-01-1-scaled.png","articleSection":["Not\u00edcias"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/zockun.com.br\/stf-mantem-a-suspensao-das-decisoes-que-afastaram-a-majoracao-das-aliquotas-do-pis-e-da-cofins-sobre-receitas-financeiras\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/zockun.com.br\/en\/stf-mantem-a-suspensao-das-decisoes-que-afastaram-a-majoracao-das-aliquotas-do-pis-e-da-cofins-sobre-receitas-financeiras\/","url":"https:\/\/zockun.com.br\/en\/stf-mantem-a-suspensao-das-decisoes-que-afastaram-a-majoracao-das-aliquotas-do-pis-e-da-cofins-sobre-receitas-financeiras\/","name":"STF mant\u00e9m a suspens\u00e3o das decis\u00f5es que afastaram a majora\u00e7\u00e3o das al\u00edquotas do PIS e da COFINS sobre receitas financeiras - Zockun e Fleury Advogados","isPartOf":{"@id":"https:\/\/zockun.com.br\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/zockun.com.br\/en\/stf-mantem-a-suspensao-das-decisoes-que-afastaram-a-majoracao-das-aliquotas-do-pis-e-da-cofins-sobre-receitas-financeiras\/#primaryimage"},"image":{"@id":"https:\/\/zockun.com.br\/stf-mantem-a-suspensao-das-decisoes-que-afastaram-a-majoracao-das-aliquotas-do-pis-e-da-cofins-sobre-receitas-financeiras\/#primaryimage"},"thumbnailUrl":"https:\/\/zockun.com.br\/wp-content\/uploads\/2026\/05\/Foto-9-01-1-scaled.png","datePublished":"2023-05-17T16:47:11+00:00","breadcrumb":{"@id":"https:\/\/zockun.com.br\/en\/stf-mantem-a-suspensao-das-decisoes-que-afastaram-a-majoracao-das-aliquotas-do-pis-e-da-cofins-sobre-receitas-financeiras\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/zockun.com.br\/en\/stf-mantem-a-suspensao-das-decisoes-que-afastaram-a-majoracao-das-aliquotas-do-pis-e-da-cofins-sobre-receitas-financeiras\/"]]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/zockun.com.br\/en\/stf-mantem-a-suspensao-das-decisoes-que-afastaram-a-majoracao-das-aliquotas-do-pis-e-da-cofins-sobre-receitas-financeiras\/#primaryimage","url":"https:\/\/zockun.com.br\/wp-content\/uploads\/2026\/05\/Foto-9-01-1-scaled.png","contentUrl":"https:\/\/zockun.com.br\/wp-content\/uploads\/2026\/05\/Foto-9-01-1-scaled.png","width":2560,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/zockun.com.br\/en\/stf-mantem-a-suspensao-das-decisoes-que-afastaram-a-majoracao-das-aliquotas-do-pis-e-da-cofins-sobre-receitas-financeiras\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/zockun.com.br\/en\/"},{"@type":"ListItem","position":2,"name":"STF mant\u00e9m a suspens\u00e3o das decis\u00f5es que afastaram a majora\u00e7\u00e3o das al\u00edquotas do PIS e da COFINS sobre receitas financeiras"}]},{"@type":"WebSite","@id":"https:\/\/zockun.com.br\/en\/#website","url":"https:\/\/zockun.com.br\/en\/","name":"Zockun e Fleury Advogados","description":"","publisher":{"@id":"https:\/\/zockun.com.br\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zockun.com.br\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/zockun.com.br\/en\/#organization","name":"Zockun e Fleury Advogados","url":"https:\/\/zockun.com.br\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/zockun.com.br\/en\/#\/schema\/logo\/image\/","url":"https:\/\/zockun.com.br\/wp-content\/uploads\/2025\/10\/Favicon.jpg","contentUrl":"https:\/\/zockun.com.br\/wp-content\/uploads\/2025\/10\/Favicon.jpg","width":400,"height":400,"caption":"Zockun e Fleury Advogados"},"image":{"@id":"https:\/\/zockun.com.br\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/zockunadvogados","https:\/\/www.linkedin.com\/company\/zockun-advogados","https:\/\/www.instagram.com\/zockunefleury\/"]},{"@type":"Person","@id":"https:\/\/zockun.com.br\/#\/schema\/person\/7b2361a745fbc8b220437ab210761a33","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/zockun.com.br"],"url":"https:\/\/zockun.com.br\/en\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/zockun.com.br\/en\/wp-json\/wp\/v2\/posts\/1341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zockun.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zockun.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zockun.com.br\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zockun.com.br\/en\/wp-json\/wp\/v2\/comments?post=1341"}],"version-history":[{"count":0,"href":"https:\/\/zockun.com.br\/en\/wp-json\/wp\/v2\/posts\/1341\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zockun.com.br\/en\/wp-json\/wp\/v2\/media\/2252"}],"wp:attachment":[{"href":"https:\/\/zockun.com.br\/en\/wp-json\/wp\/v2\/media?parent=1341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zockun.com.br\/en\/wp-json\/wp\/v2\/categories?post=1341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}