{"id":1286,"date":"2023-03-27T17:15:16","date_gmt":"2023-03-27T20:15:16","guid":{"rendered":"http:\/\/www.zockun.com.br\/?p=1286"},"modified":"2023-03-27T17:15:16","modified_gmt":"2023-03-27T20:15:16","slug":"regulamentada-a-aplicacao-de-sancoes-por-ofensa-a-lgpd","status":"publish","type":"post","link":"https:\/\/zockun.com.br\/en\/regulamentada-a-aplicacao-de-sancoes-por-ofensa-a-lgpd\/","title":{"rendered":"Regulamentada a aplica\u00e7\u00e3o de san\u00e7\u00f5es por ofensa \u00e0 LGPD  \u00a0"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>O art. 55-J, IV, da Lei Geral de Prote\u00e7\u00e3o de Dados (LGPD), atribui \u00e0\u00a0Autoridade Nacional de Prote\u00e7\u00e3o de Dados (ANPD) a compet\u00eancia\u00a0para fiscalizar e sancionar quem realizar o tratamento de dados realizados em descumprimento \u00e0 legisla\u00e7\u00e3o.<\/p>\n<p>&nbsp;<\/p>\n<p>A metodologia para aplica\u00e7\u00e3o da penalidades aplic\u00e1veis, no entanto, estava condicionado \u00e0 regulamenta\u00e7\u00e3o da mat\u00e9ria pela ANPD, o que ocorreu no \u00faltimo dia 27\/2\/2023, com a publica\u00e7\u00e3o do\u00a0<a href=\"https:\/\/www.gov.br\/anpd\/pt-br\/assuntos\/noticias\/anpd-publica-regulamento-de-dosimetria\/Resolucaon4CDANPD24.02.2023.pdf\">Regulamento de Dosimetria e Aplica\u00e7\u00e3o de San\u00e7\u00f5es Administrativas editado pela ANPD<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; O art. 55-J, IV, da Lei Geral de Prote\u00e7\u00e3o de Dados (LGPD), atribui \u00e0\u00a0Autoridade Nacional de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2258,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[8],"class_list":["post-1286","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Regulamentada a aplica\u00e7\u00e3o de san\u00e7\u00f5es por ofensa \u00e0 LGPD \u00a0 - Zockun e Fleury Advogados<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zockun.com.br\/en\/regulamentada-a-aplicacao-de-sancoes-por-ofensa-a-lgpd\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Regulamentada a aplica\u00e7\u00e3o de san\u00e7\u00f5es por ofensa \u00e0 LGPD \u00a0 - Zockun e Fleury Advogados\" \/>\n<meta property=\"og:description\" content=\"&nbsp; O art. 55-J, IV, da Lei Geral de Prote\u00e7\u00e3o de Dados (LGPD), atribui \u00e0\u00a0Autoridade Nacional de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zockun.com.br\/en\/regulamentada-a-aplicacao-de-sancoes-por-ofensa-a-lgpd\/\" \/>\n<meta property=\"og:site_name\" content=\"Zockun e Fleury Advogados\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/zockunadvogados\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-27T20:15:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zockun.com.br\/wp-content\/uploads\/2026\/05\/Foto-9-07-1024x576.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/zockun.com.br\\\/regulamentada-a-aplicacao-de-sancoes-por-ofensa-a-lgpd\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/regulamentada-a-aplicacao-de-sancoes-por-ofensa-a-lgpd\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/zockun.com.br\\\/#\\\/schema\\\/person\\\/7b2361a745fbc8b220437ab210761a33\"},\"headline\":\"Regulamentada a aplica\u00e7\u00e3o de san\u00e7\u00f5es por ofensa \u00e0 LGPD \u00a0\",\"datePublished\":\"2023-03-27T20:15:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/regulamentada-a-aplicacao-de-sancoes-por-ofensa-a-lgpd\\\/\"},\"wordCount\":96,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/regulamentada-a-aplicacao-de-sancoes-por-ofensa-a-lgpd\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zockun.com.br\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Foto-9-07-scaled.png\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/zockun.com.br\\\/regulamentada-a-aplicacao-de-sancoes-por-ofensa-a-lgpd\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/regulamentada-a-aplicacao-de-sancoes-por-ofensa-a-lgpd\\\/\",\"url\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/regulamentada-a-aplicacao-de-sancoes-por-ofensa-a-lgpd\\\/\",\"name\":\"Regulamentada a aplica\u00e7\u00e3o de san\u00e7\u00f5es por ofensa \u00e0 LGPD \u00a0 - Zockun e Fleury Advogados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/regulamentada-a-aplicacao-de-sancoes-por-ofensa-a-lgpd\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/regulamentada-a-aplicacao-de-sancoes-por-ofensa-a-lgpd\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zockun.com.br\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Foto-9-07-scaled.png\",\"datePublished\":\"2023-03-27T20:15:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/regulamentada-a-aplicacao-de-sancoes-por-ofensa-a-lgpd\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/zockun.com.br\\\/en\\\/regulamentada-a-aplicacao-de-sancoes-por-ofensa-a-lgpd\\\/\"]]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/regulamentada-a-aplicacao-de-sancoes-por-ofensa-a-lgpd\\\/#primaryimage\",\"url\":\"https:\\\/\\\/zockun.com.br\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Foto-9-07-scaled.png\",\"contentUrl\":\"https:\\\/\\\/zockun.com.br\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Foto-9-07-scaled.png\",\"width\":2560,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/regulamentada-a-aplicacao-de-sancoes-por-ofensa-a-lgpd\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Regulamentada a aplica\u00e7\u00e3o de san\u00e7\u00f5es por ofensa \u00e0 LGPD \u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/\",\"name\":\"Zockun e Fleury Advogados\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/#organization\",\"name\":\"Zockun e Fleury Advogados\",\"url\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/zockun.com.br\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Favicon.jpg\",\"contentUrl\":\"https:\\\/\\\/zockun.com.br\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Favicon.jpg\",\"width\":400,\"height\":400,\"caption\":\"Zockun e Fleury Advogados\"},\"image\":{\"@id\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/zockunadvogados\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/zockun-advogados\",\"https:\\\/\\\/www.instagram.com\\\/zockunefleury\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/zockun.com.br\\\/#\\\/schema\\\/person\\\/7b2361a745fbc8b220437ab210761a33\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/zockun.com.br\"],\"url\":\"https:\\\/\\\/zockun.com.br\\\/en\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Regulamentada a aplica\u00e7\u00e3o de san\u00e7\u00f5es por ofensa \u00e0 LGPD \u00a0 - Zockun e Fleury Advogados","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zockun.com.br\/en\/regulamentada-a-aplicacao-de-sancoes-por-ofensa-a-lgpd\/","og_locale":"en_US","og_type":"article","og_title":"Regulamentada a aplica\u00e7\u00e3o de san\u00e7\u00f5es por ofensa \u00e0 LGPD \u00a0 - Zockun e Fleury Advogados","og_description":"&nbsp; O art. 55-J, IV, da Lei Geral de Prote\u00e7\u00e3o de Dados (LGPD), atribui \u00e0\u00a0Autoridade Nacional de [&hellip;]","og_url":"https:\/\/zockun.com.br\/en\/regulamentada-a-aplicacao-de-sancoes-por-ofensa-a-lgpd\/","og_site_name":"Zockun e Fleury Advogados","article_publisher":"https:\/\/www.facebook.com\/zockunadvogados","article_published_time":"2023-03-27T20:15:16+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/zockun.com.br\/wp-content\/uploads\/2026\/05\/Foto-9-07-1024x576.png","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/zockun.com.br\/regulamentada-a-aplicacao-de-sancoes-por-ofensa-a-lgpd\/#article","isPartOf":{"@id":"https:\/\/zockun.com.br\/regulamentada-a-aplicacao-de-sancoes-por-ofensa-a-lgpd\/"},"author":{"name":"admin","@id":"https:\/\/zockun.com.br\/#\/schema\/person\/7b2361a745fbc8b220437ab210761a33"},"headline":"Regulamentada a aplica\u00e7\u00e3o de san\u00e7\u00f5es por ofensa \u00e0 LGPD \u00a0","datePublished":"2023-03-27T20:15:16+00:00","mainEntityOfPage":{"@id":"https:\/\/zockun.com.br\/regulamentada-a-aplicacao-de-sancoes-por-ofensa-a-lgpd\/"},"wordCount":96,"commentCount":0,"publisher":{"@id":"https:\/\/zockun.com.br\/#organization"},"image":{"@id":"https:\/\/zockun.com.br\/regulamentada-a-aplicacao-de-sancoes-por-ofensa-a-lgpd\/#primaryimage"},"thumbnailUrl":"https:\/\/zockun.com.br\/wp-content\/uploads\/2026\/05\/Foto-9-07-scaled.png","articleSection":["Not\u00edcias"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/zockun.com.br\/regulamentada-a-aplicacao-de-sancoes-por-ofensa-a-lgpd\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/zockun.com.br\/en\/regulamentada-a-aplicacao-de-sancoes-por-ofensa-a-lgpd\/","url":"https:\/\/zockun.com.br\/en\/regulamentada-a-aplicacao-de-sancoes-por-ofensa-a-lgpd\/","name":"Regulamentada a aplica\u00e7\u00e3o de san\u00e7\u00f5es por ofensa \u00e0 LGPD \u00a0 - Zockun e Fleury Advogados","isPartOf":{"@id":"https:\/\/zockun.com.br\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/zockun.com.br\/en\/regulamentada-a-aplicacao-de-sancoes-por-ofensa-a-lgpd\/#primaryimage"},"image":{"@id":"https:\/\/zockun.com.br\/regulamentada-a-aplicacao-de-sancoes-por-ofensa-a-lgpd\/#primaryimage"},"thumbnailUrl":"https:\/\/zockun.com.br\/wp-content\/uploads\/2026\/05\/Foto-9-07-scaled.png","datePublished":"2023-03-27T20:15:16+00:00","breadcrumb":{"@id":"https:\/\/zockun.com.br\/en\/regulamentada-a-aplicacao-de-sancoes-por-ofensa-a-lgpd\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/zockun.com.br\/en\/regulamentada-a-aplicacao-de-sancoes-por-ofensa-a-lgpd\/"]]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/zockun.com.br\/en\/regulamentada-a-aplicacao-de-sancoes-por-ofensa-a-lgpd\/#primaryimage","url":"https:\/\/zockun.com.br\/wp-content\/uploads\/2026\/05\/Foto-9-07-scaled.png","contentUrl":"https:\/\/zockun.com.br\/wp-content\/uploads\/2026\/05\/Foto-9-07-scaled.png","width":2560,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/zockun.com.br\/en\/regulamentada-a-aplicacao-de-sancoes-por-ofensa-a-lgpd\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/zockun.com.br\/en\/"},{"@type":"ListItem","position":2,"name":"Regulamentada a aplica\u00e7\u00e3o de san\u00e7\u00f5es por ofensa \u00e0 LGPD \u00a0"}]},{"@type":"WebSite","@id":"https:\/\/zockun.com.br\/en\/#website","url":"https:\/\/zockun.com.br\/en\/","name":"Zockun e Fleury Advogados","description":"","publisher":{"@id":"https:\/\/zockun.com.br\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zockun.com.br\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/zockun.com.br\/en\/#organization","name":"Zockun e Fleury Advogados","url":"https:\/\/zockun.com.br\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/zockun.com.br\/en\/#\/schema\/logo\/image\/","url":"https:\/\/zockun.com.br\/wp-content\/uploads\/2025\/10\/Favicon.jpg","contentUrl":"https:\/\/zockun.com.br\/wp-content\/uploads\/2025\/10\/Favicon.jpg","width":400,"height":400,"caption":"Zockun e Fleury Advogados"},"image":{"@id":"https:\/\/zockun.com.br\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/zockunadvogados","https:\/\/www.linkedin.com\/company\/zockun-advogados","https:\/\/www.instagram.com\/zockunefleury\/"]},{"@type":"Person","@id":"https:\/\/zockun.com.br\/#\/schema\/person\/7b2361a745fbc8b220437ab210761a33","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c905ba65424bc99d600b3220e8713eaf72b4dd68497ef6722b4375ad88fd5817?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/zockun.com.br"],"url":"https:\/\/zockun.com.br\/en\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/zockun.com.br\/en\/wp-json\/wp\/v2\/posts\/1286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zockun.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zockun.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zockun.com.br\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zockun.com.br\/en\/wp-json\/wp\/v2\/comments?post=1286"}],"version-history":[{"count":0,"href":"https:\/\/zockun.com.br\/en\/wp-json\/wp\/v2\/posts\/1286\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zockun.com.br\/en\/wp-json\/wp\/v2\/media\/2258"}],"wp:attachment":[{"href":"https:\/\/zockun.com.br\/en\/wp-json\/wp\/v2\/media?parent=1286"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zockun.com.br\/en\/wp-json\/wp\/v2\/categories?post=1286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}